{"id":1663,"date":"2023-12-22T13:00:10","date_gmt":"2023-12-22T13:00:10","guid":{"rendered":"https:\/\/ruxtonconsultancy.com\/sil-thonen-de\/inzwischen-in-lagos-teil-l\/"},"modified":"2023-12-22T13:07:13","modified_gmt":"2023-12-22T13:07:13","slug":"inzwischen-in-lagos-teil-l","status":"publish","type":"post","link":"https:\/\/www.ruxtonconsultancy.com\/de\/inzwischen-in-lagos-teil-l\/","title":{"rendered":"Inzwischen in Lagos&#8230;.. Teil L"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1663\" class=\"elementor elementor-1663 elementor-1650\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-143051a e-flex e-con-boxed e-con e-parent\" data-id=\"143051a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ce153f elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"0ce153f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"307\" src=\"https:\/\/www.ruxtonconsultancy.com\/wp-content\/uploads\/2023\/12\/1695902918125-1024x307.png\" class=\"attachment-large size-large wp-image-1658\" alt=\"\" srcset=\"https:\/\/www.ruxtonconsultancy.com\/wp-content\/uploads\/2023\/12\/1695902918125-1024x307.png 1024w, https:\/\/www.ruxtonconsultancy.com\/wp-content\/uploads\/2023\/12\/1695902918125-300x90.png 300w, https:\/\/www.ruxtonconsultancy.com\/wp-content\/uploads\/2023\/12\/1695902918125-768x230.png 768w, https:\/\/www.ruxtonconsultancy.com\/wp-content\/uploads\/2023\/12\/1695902918125-1536x461.png 1536w, https:\/\/www.ruxtonconsultancy.com\/wp-content\/uploads\/2023\/12\/1695902918125.png 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-134d76c elementor-widget elementor-widget-text-editor\" data-id=\"134d76c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Teil L&#8230;, oder Teil 50. 50 St\u00fcck in ein paar Jahren. Es ist ein sch\u00f6nes Zeitbild von unserem Abenteuer in Nigeria geworden. Ich lese die St\u00fccke immer noch von Zeit zu Zeit. Vor allem auch, weil ich mich nicht wiederholen will. Nicht nur f\u00fcr Sie als Leser, sondern auch, weil ich mich manchmal dabei ertappe, wie ich wie ein alter Miesepeter schwanke. Ich mochte (und mag immer noch) bestimmte Leute in den Expat-Gemeinschaften nicht. Man kennt sie, stark schwitzend, meist viel \u00fcber sich selbst redend, ein bisschen zu dick, zu gro\u00dfer Specknacken, politisch eher rechts orientiert, wahrscheinlich als letztes beim Turnen ausgew\u00e4hlt worden und pl\u00f6tzlich die gro\u00dfe Dame\/Mann. Nun, bei jeder Zusammenkunft von Gruppen gibt es diese Art von Figuren, also war das irgendwie zu erwarten.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d195743 elementor-widget elementor-widget-text-editor\" data-id=\"d195743\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p id=\"ember1985\" class=\"ember-view reader-content-blocks__paragraph\">Was mir bereits bei meinem Besuch in Nigeria aufgefallen war, war die beispiellose F\u00e4higkeit von Expats, sich zu beschweren, gepaart mit einer manchmal etwas abf\u00e4lligen Haltung gegen\u00fcber nigerianischen Kollegen und\/oder Mitarbeitern. Besonders beim Heruntersp\u00fclen des 4. Gin&amp;Tonic. Dass dieser 4. G&amp;T eine Rechnung bedeutet, die fast einem Wochenlohn eines durchschnittlichen Nigerianers entspricht, ist offenbar irrelevant&#8230;.<\/p>\n<p id=\"ember1986\" class=\"ember-view reader-content-blocks__paragraph\">Damals beschloss ich, dass ich das nie tun w\u00fcrde. Ich habe mich immer noch vor dem Spiegel ermahnt und mir ein paar einfache Regeln zurechtgelegt. Lebensregeln, die auch die Grundlage daf\u00fcr bilden, wie ich meine Kinder erziehe. Sollten Sie jemals meinem j\u00fcngsten Sohn begegnen&#8230; er kennt sie auswendig:<\/p>\n<ol>\n<li>erst denken, dann tun<\/li>\n<li>Wenn Sie nichts Nettes sagen k\u00f6nnen, sagen Sie gar nichts<\/li>\n<li>wenn es nicht deines ist, bleib weg von ihm<\/li>\n<\/ol>\n<p id=\"ember1988\" class=\"ember-view reader-content-blocks__paragraph\">Die Regel 2 ist in dieser Hinsicht besonders interessant. Mir wurde von zu Hause aus beigebracht, immer freundlich zu sein und vor allem die Meinungen und \u00dcberzeugungen anderer zu respektieren&#8230; usw. Respekt. Au\u00dferdem sollten Sie immer bedenken, dass eine andere Person wahrscheinlich eine andere Sichtweise hat, weil sie einfach nicht die gleiche Erziehung oder die gleichen M\u00f6glichkeiten erhalten hat. Wir sind also immer noch bei Regel 1 gelandet, und ich nehme an, dass ich Regel 3 nicht weiter erkl\u00e4ren muss&#8230; obwohl Nigerianer manchmal anders denken.<\/p>\n<p id=\"ember1989\" class=\"ember-view reader-content-blocks__paragraph\">Wenn ich dann wieder einmal zuf\u00e4llig auf einer dummen Veranstaltung lande und mich ungl\u00fccklicherweise an einen dieser Speckh\u00e4lse lehne, denke ich immer an diesen Moment vor dem Spiegel zur\u00fcck. Lassen Sie mich Ihnen kurz den Schauplatz zeigen, damit Sie eine kleine Vorstellung davon bekommen. Oft wird ein solches Treffen organisiert, weil eine kleine Aktivit\u00e4t unserer k\u00f6niglichen Familie in einem weit entfernten Land stattfindet. Dann werden ein paar Tische aufgestellt, der \u00f6rtliche Zuh\u00e4lter ist wieder einmal versucht, Freibier auszuschenken, und der neue Gast aus dem Ausland trifft zur angek\u00fcndigten Zeit in Anz\u00fcgen ein. Ich selbst habe inzwischen gelernt, dass es in Ordnung ist, erst um 21.00 Uhr zu erscheinen, wenn auf der Einladung 20.00 Uhr steht, und ich habe schon seit Jahren keinen Anzug mehr getragen (geschweige denn eine Krawatte). Bei 32 Grad ist es auch nicht machbar, aber das ist vielleicht eine pers\u00f6nliche Sache.<\/p>\n<p id=\"ember1990\" class=\"ember-view reader-content-blocks__paragraph\">Ein sch\u00f6nes Beispiel war der K\u00f6nigstag vor einigen Jahren im niederl\u00e4ndischen Konsulat in Lagos. Fair ist fair, das Konsulat hat sein Bestes getan, um sich um alles zu k\u00fcmmern. Es wurde sogar Hering mit Orangenbittereingeflogen. Das gef\u00e4llt mir schon in den Niederlanden nicht, aber die Geste ist auf jeden Fall zu begr\u00fc\u00dfen. Ich kam <em>mit angemessener <\/em>Versp\u00e4tung an, weil ich die Rede des Gouverneurs von Lagos gerne verpasst h\u00e4tte, aber leider hatte auch er beschlossen, dass die Anfangszeit nicht f\u00fcr ihn gilt. Und ehe ich mich versah, stand ich an einem Formica-Stehtisch mit einem stinkenden Teller lauwarmen Fischs, gespickt mit einem leuchtenden Orangenbitter in den H\u00e4nden. Ich war offenbar etwas verloren, denn pl\u00f6tzlich stand eine nordeurop\u00e4isch anmutende Dame neben mir. Typ Faltenrock, blauer Lidschatten, hochbeinig, \u00fcberlange Expat-Frau und ein sehr gro\u00dfer Mund mit Ditto-Kartoffel in der Kehle. Ich hatte kaum Zeit, mich richtig vorzustellen, denn sie hatte offensichtlich etwas zu sagen.<\/p>\n<p id=\"ember1991\" class=\"ember-view reader-content-blocks__paragraph\">Die betreffende Dame platzte fast vor Gl\u00fcck, weil sie endlich wieder in der Zivilisation war. Sie und ihr Mann hatten einige Jahre in dem, wie sie es selbst nannte,<em>&#8222;Drecksloch Gottes<\/em>&#8220; verbracht, n\u00e4mlich in der \u00f6l- und gasreichen Gegend um Port Harcourt. Nun bin ich auch manchmal in diesen Gegenden unterwegs, und es gibt in der Tat sch\u00f6nere Orte, aber ich habe es noch nie so schlimm erlebt, wie sie es darstellte. Ich war nicht sonderlich an ihrer Geschichte interessiert, aber ein wenig Ansto\u00df kann nicht schaden, und so teilte ich ihr mit, dass es doch nicht so schlimm sein k\u00f6nne, wie sie behauptete.<\/p>\n<p id=\"ember1992\" class=\"ember-view reader-content-blocks__paragraph\">Der Hehler war daraufhin v\u00f6llig aus dem H\u00e4uschen, und neben all den Geschichten rund um die gro\u00dfe <em>Not <\/em>wurde mir auch fein s\u00e4uberlich erz\u00e4hlt, dass offenbar alle nigerianischen Frauen hinter ihrem Mann her gewesen seien. Sie hatte sogar verlangt, dass die \u00d6lfirma, f\u00fcr die ihr Mann arbeitete, eine andere Sekret\u00e4rin einstellte, da die erste auch ihrem Adonis hinterher geglotzt hatte. Nat\u00fcrlich hatte der geliebte Ehemann den Kurs gewechselt, und die erste Sekret\u00e4rin war freundlich gebeten worden, sich eine andere Stelle zu suchen. Voller Stolz sah sie mich an, als k\u00f6nne ich nichts anderes tun, als zu best\u00e4tigen, dass die Welt offenbar so funktioniert.<\/p>\n<p id=\"ember1993\" class=\"ember-view reader-content-blocks__paragraph\">Meine Frage, ob sie wusste, wo diese erste Sekret\u00e4rin damals gelandet war, und ob es tats\u00e4chlich Beweise f\u00fcr den angeblichen Ehebruch ihres Mannes gab, h\u00e4tte ich besser f\u00fcr mich behalten sollen. Das Gespr\u00e4ch war pl\u00f6tzlich zu Ende und sie machte sich auf die Suche nach einem anderen willigen Opfer. Wie ich k\u00fcrzlich erfuhr, hat sich der betreffende Trauzeuge wieder in Port Harcourt niedergelassen und ist sehr gl\u00fccklich mit seiner neuen nigerianischen Frau, aber das nur nebenbei.<\/p>\n<p id=\"ember1994\" class=\"ember-view reader-content-blocks__paragraph\">Ich kann es dieser Frau auch nicht ver\u00fcbeln. Vor allem die in Nigeria t\u00e4tigen \u00d6l- und Gasunternehmen erlegen allen ihren Expatriates erhebliche Beschr\u00e4nkungen auf. Das ist in Lagos bereits der Fall, aber in Port Harcourt ist es wirklich kein Spa\u00df. Arbeiten kommt f\u00fcr diese (oft hoch gebildeten) Frauen nicht in Frage, und viel mehr als der w\u00f6chentliche Ausflug zum Supermarkt und freitags zum Expat-Golf-, Segel- und\/oder Cricket-Club kommt nicht in Frage. Auch die Freitagabende sehen in der Regel gleich aus: die M\u00e4nner sitzen zusammen und nutzen den Abend, um sich besser zu vernetzen, und die Frauen streiten sich dar\u00fcber, wo es diese Woche Brokkoli zu kaufen gab. In solchen Situationen suchen die Menschen dann nach Gespr\u00e4chsthemen, und leider lauert dann das Jammern. Denn nichts l\u00e4sst das eigene Leben sch\u00f6ner aussehen, als wenn man es mit etwas &#8222;Schrecklichem&#8220; kontrastieren kann. Das Leben im Ausland erfordert daher vor allem eine gute Beziehung, die auf dem Konzept des<em>&#8222;Wir<\/em>&#8220; basiert. Zusammenarbeit f\u00fcr die gemeinsame BV, in der jeder Partner seine Rolle hat.<\/p>\n<p id=\"ember1995\" class=\"ember-view reader-content-blocks__paragraph\">Auf jeden Fall bin ich sehr froh, dass ich einen Gro\u00dfteil dieser besonderen Zeit von 50 St\u00fccken mit meiner Frau und meinen Kindern teilen konnte. In den letzten zwei Jahren war ich allein in diesem wunderbaren Land, und das macht nicht immer viel Spa\u00df. Zum Gl\u00fcck habe ich keine glotzenden nigerianischen Frauen, die mein Interesse wecken, aber das liegt nur an meinem Partner, der genau sp\u00fcrt, welche Unterst\u00fctzung ich brauche, und zu 100 % hinter meinen Entscheidungen steht.<\/p>\n<p id=\"ember1996\" class=\"ember-view reader-content-blocks__paragraph\">Dieser Beitrag ist also haupts\u00e4chlich f\u00fcr meine Frau im Ausland, meinen Felsen und meinen G&amp;T-Kumpel!<\/p>\n<p id=\"ember1997\" class=\"ember-view reader-content-blocks__paragraph\">Bis zum n\u00e4chsten Monat!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-86faaa0 e-flex e-con-boxed e-con e-parent\" data-id=\"86faaa0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c007da elementor-widget elementor-widget-spacer\" data-id=\"1c007da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b10cf33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b10cf33\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-93c828a\" data-id=\"93c828a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce9b67d elementor-widget elementor-widget-image\" data-id=\"ce9b67d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"432\" height=\"438\" src=\"https:\/\/www.ruxtonconsultancy.com\/wp-content\/uploads\/2023\/12\/pasfoto-smc-thonen-1.png\" class=\"attachment-full size-full wp-image-1552\" alt=\"\" srcset=\"https:\/\/www.ruxtonconsultancy.com\/wp-content\/uploads\/2023\/12\/pasfoto-smc-thonen-1.png 432w, https:\/\/www.ruxtonconsultancy.com\/wp-content\/uploads\/2023\/12\/pasfoto-smc-thonen-1-296x300.png 296w\" sizes=\"(max-width: 432px) 100vw, 432px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-adfafbe\" data-id=\"adfafbe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c055ad4 elementor-widget elementor-widget-heading\" data-id=\"c055ad4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wie kann ich Ihnen helfen?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8441f2 elementor-widget elementor-widget-heading\" data-id=\"f8441f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Wir helfen Unternehmen, in einer sich schnell ver\u00e4ndernden Welt die Nase vorn zu haben.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fb844e elementor-widget elementor-widget-button\" data-id=\"4fb844e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ruxtonconsultancy.com\/de\/kontakt\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Gespr\u00e4ch mit Sil<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Teil L&#8230;, oder Teil 50. 50 St\u00fcck in ein paar Jahren. Es ist ein sch\u00f6nes Zeitbild von unserem Abenteuer in Nigeria geworden. Ich lese die St\u00fccke immer noch von Zeit zu Zeit. Vor allem auch, weil ich mich nicht wiederholen will. Nicht nur f\u00fcr Sie als Leser, sondern auch, weil ich mich manchmal dabei ertappe, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1658,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[22],"tags":[],"class_list":["post-1663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sil-thonen-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ruxtonconsultancy.com\/de\/wp-json\/wp\/v2\/posts\/1663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ruxtonconsultancy.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ruxtonconsultancy.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ruxtonconsultancy.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ruxtonconsultancy.com\/de\/wp-json\/wp\/v2\/comments?post=1663"}],"version-history":[{"count":1,"href":"https:\/\/www.ruxtonconsultancy.com\/de\/wp-json\/wp\/v2\/posts\/1663\/revisions"}],"predecessor-version":[{"id":1664,"href":"https:\/\/www.ruxtonconsultancy.com\/de\/wp-json\/wp\/v2\/posts\/1663\/revisions\/1664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ruxtonconsultancy.com\/de\/wp-json\/wp\/v2\/media\/1658"}],"wp:attachment":[{"href":"https:\/\/www.ruxtonconsultancy.com\/de\/wp-json\/wp\/v2\/media?parent=1663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ruxtonconsultancy.com\/de\/wp-json\/wp\/v2\/categories?post=1663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ruxtonconsultancy.com\/de\/wp-json\/wp\/v2\/tags?post=1663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}