{"id":1882,"date":"2023-11-30T12:14:36","date_gmt":"2023-11-30T12:14:36","guid":{"rendered":"https:\/\/ruxtonconsultancy.com\/non-classifiee\/pendant-ce-temps-a-lagos-partie-ii\/"},"modified":"2023-11-30T12:14:36","modified_gmt":"2023-11-30T12:14:36","slug":"pendant-ce-temps-a-lagos-partie-ii","status":"publish","type":"post","link":"https:\/\/www.ruxtonconsultancy.com\/fr\/pendant-ce-temps-a-lagos-partie-ii\/","title":{"rendered":"Pendant ce temps \u00e0 Lagos&#8230;..Partie II"},"content":{"rendered":"<p id=\"ember382\" class=\"ember-view reader-content-blocks__paragraph\">Nous sommes \u00e0 la fin du mois de novembre 2024. Les derni\u00e8res semaines de l&rsquo;ann\u00e9e active au Nigeria sont \u00e0 nos portes. \u00c0 partir de la semaine 50, il ne se passera plus grand-chose et tout le monde attendra No\u00ebl avec impatience. Il est donc temps de r\u00e9fl\u00e9chir un peu et peut-\u00eatre oserai-je me projeter en 2024.<\/p>\n<p id=\"ember383\" class=\"ember-view reader-content-blocks__paragraph\">Les derniers mois ont \u00e9t\u00e9 tr\u00e8s difficiles pour le Nig\u00e9rian moyen. L&rsquo;entr\u00e9e en fonction du nouveau pr\u00e9sident et de son cabinet a imm\u00e9diatement conduit \u00e0 la mise en \u0153uvre de mesures tr\u00e8s drastiques (mais n\u00e9cessaires) qui ont frapp\u00e9 tout le monde de plein fouet. J&rsquo;ai d\u00e9j\u00e0 mentionn\u00e9 les \u00e9normes taux d&rsquo;inflation, mais maintenant qu&rsquo;ils ont \u00e9t\u00e9 aggrav\u00e9s par une d\u00e9valuation stup\u00e9fiante de la monnaie nationale, c&rsquo;est vraiment la pauvret\u00e9. En \u00e0 peine six mois, le naira a connu une chute libre \u00e0 laquelle des pays comme le Zimbabwe et, dans une moindre mesure, la Turquie ne nous avaient habitu\u00e9s que ces derni\u00e8res ann\u00e9es. Cela d\u00e9pend un peu des taux que l&rsquo;on regarde et que l&rsquo;on croit, mais j&rsquo;ai d\u00e9j\u00e0 vu passer des chiffres de d\u00e9valuation de plus de 60 %. Le fait est que le march\u00e9 parall\u00e8le (au sein duquel le Nig\u00e9rian doit faire ses achats dans la rue), affichait un taux de 740 nairas pour un dollar en juin 2023 et que ce matin, le dollar \u00e9tait d\u00e9j\u00e0 bien au-dessus de 1,150 nairas.<\/p>\n<p>Ces chiffres d\u00e9passent l&rsquo;entendement d&rsquo;un N\u00e9erlandais moyen. Cela est particuli\u00e8rement \u00e9vident si l&rsquo;on examine les discussions qui ont eu lieu lors de la derni\u00e8re campagne \u00e9lectorale n\u00e9erlandaise. J&rsquo;ai suivi cette affaire avec int\u00e9r\u00eat, ne serait-ce que parce qu&rsquo;en tant qu&rsquo;expatri\u00e9, je ne suis autoris\u00e9 \u00e0 voter que lors des \u00e9lections de la deuxi\u00e8me chambre. Ce qui m&rsquo;a frapp\u00e9 dans toute la rh\u00e9torique \u00e9lectorale, c&rsquo;est l&rsquo;utilisation fr\u00e9quente du mot<em>\u00ab\u00a0s\u00e9curit\u00e9 des moyens de subsistance<\/em>\u00ab\u00a0. Outre la valeur de 32 au Scrabble, il s&rsquo;agit d&rsquo;un label que je n&rsquo;arrive pas \u00e0 identifier. Qui d\u00e9termine donc exactement ce qu&rsquo;est la s\u00e9curit\u00e9 de subsistance ? Pouvez-vous mesurer cela ? Par rapport \u00e0 quel minimum cette soi-disant s\u00e9curit\u00e9 est-elle pond\u00e9r\u00e9e&#8230; enfin vous me comprenez. Il y a tr\u00e8s longtemps, j&rsquo;ai pass\u00e9 un lundi bleu \u00e0 la facult\u00e9 de droit de Nim\u00e8gue. D\u00e9j\u00e0 \u00e0 l&rsquo;\u00e9poque, j&rsquo;ai \u00e9t\u00e9 frapp\u00e9 par le fait que la principale mati\u00e8re enseign\u00e9e \u00e0 nos juristes en herbe est l&rsquo;\u00e9thique et la philosophie. En d&rsquo;autres termes, qu&rsquo;est-ce qui me donne le droit d&rsquo;imposer un cadre juridique \u00e0 un autre et qui ou quoi d\u00e9termine ce cadre ?<\/p>\n<div class=\"reader-image-block reader-image-block--full-width\">\n<figure class=\"reader-image-block__figure\">\n<div class=\"ivm-image-view-model \">\n<div class=\"ivm-view-attr__img-wrapper display-flex\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large wp-image-1536\" src=\"https:\/\/ruxtonconsultancy.com\/wp-content\/uploads\/2023\/12\/1701359858998-1024x576.jpeg\" alt=\"\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.ruxtonconsultancy.com\/wp-content\/uploads\/2023\/12\/1701359858998-1024x576.jpeg 1024w, https:\/\/www.ruxtonconsultancy.com\/wp-content\/uploads\/2023\/12\/1701359858998-300x169.jpeg 300w, https:\/\/www.ruxtonconsultancy.com\/wp-content\/uploads\/2023\/12\/1701359858998-768x432.jpeg 768w, https:\/\/www.ruxtonconsultancy.com\/wp-content\/uploads\/2023\/12\/1701359858998.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<p id=\"ember386\" class=\"ember-view reader-content-blocks__paragraph\">La facult\u00e9 de droit de mon Alma Mater donne la d\u00e9finition suivante<em>: \u00ab\u00a0Le droit aborde les relations en mettant fortement l&rsquo;accent sur les int\u00e9r\u00eats \u00e0 faire valoir. L&rsquo;\u00e9thique met l&rsquo;accent sur les valeurs partag\u00e9es, l&rsquo;attention et la compassion. Le droit concerne les r\u00e8gles de port\u00e9e g\u00e9n\u00e9rale. En \u00e9thique, les questions sont tr\u00e8s sensibles au contexte. <\/em> J&rsquo;ai toujours pens\u00e9 que les deux \u00e9taient ins\u00e9parables et que les int\u00e9r\u00eats \u00e0 revendiquer ne pouvaient \u00eatre s\u00e9par\u00e9s d&rsquo;un contexte \u00e9thique. L&rsquo;id\u00e9e qu&rsquo;il existe une diff\u00e9rence entre les deux et que l&rsquo;un peut \u00eatre s\u00e9par\u00e9 de l&rsquo;autre me laisse donc perplexe. Surtout quand on sait que Thomas d&rsquo;Aquin lui-m\u00eame surplombe l&rsquo;\u00e9cole de droit dans le domaine de Heyendaal, mais vous, le lecteur, pouvez r\u00e9soudre cette \u00e9nigme vous-m\u00eame. #<em>De regimine principum.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous sommes \u00e0 la fin du mois de novembre 2024. Les derni\u00e8res semaines de l&rsquo;ann\u00e9e active au Nigeria sont \u00e0 nos portes. \u00c0 partir de la semaine 50, il ne se passera plus grand-chose et tout le monde attendra No\u00ebl avec impatience. Il est donc temps de r\u00e9fl\u00e9chir un peu et peut-\u00eatre oserai-je me projeter [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1885,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[39],"tags":[],"class_list":["post-1882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ruxtonconsultancy.com\/fr\/wp-json\/wp\/v2\/posts\/1882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ruxtonconsultancy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ruxtonconsultancy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ruxtonconsultancy.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ruxtonconsultancy.com\/fr\/wp-json\/wp\/v2\/comments?post=1882"}],"version-history":[{"count":0,"href":"https:\/\/www.ruxtonconsultancy.com\/fr\/wp-json\/wp\/v2\/posts\/1882\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ruxtonconsultancy.com\/fr\/wp-json\/wp\/v2\/media\/1885"}],"wp:attachment":[{"href":"https:\/\/www.ruxtonconsultancy.com\/fr\/wp-json\/wp\/v2\/media?parent=1882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ruxtonconsultancy.com\/fr\/wp-json\/wp\/v2\/categories?post=1882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ruxtonconsultancy.com\/fr\/wp-json\/wp\/v2\/tags?post=1882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}